{"id":11303,"date":"2022-06-30T15:00:11","date_gmt":"2022-06-30T19:00:11","guid":{"rendered":"http:\/\/pumahue.cl\/chicauma\/?p=11303"},"modified":"2022-06-30T15:00:11","modified_gmt":"2022-06-30T19:00:11","slug":"segunda-jornada-de-convivencia-escolar","status":"publish","type":"post","link":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/","title":{"rendered":"Segunda Jornada de Convivencia Escolar"},"content":{"rendered":"<p>En esta instancia, a trav\u00e9s de las Comunidades de curso, los estudiantes pudieron revisar y reestructurar en caso de ser necesario, su \u201cContrato de curso\u201d\u009d (compromisos y normas que establecieron los alumnos junto a su profesor\/a desde principio de a\u00f1o con buenas pr\u00e1cticas de convivencia), con el fin de visualizar fortalezas y debilidades durante el semestre transcurrido y prepararnos para el semestre que viene.<\/p>\n<p>Adem\u00e1s de lo se\u00f1alado, durante las Comunidades de curso realizadas el d\u00eda de ayer, se reforz\u00f3 la identidad de cada curso, nuestro ADN Chicauma y nuestro Programa + Respect + Fun a trav\u00e9s de diversas actividades l\u00fadicas.  Junto con lo anterior, cada curso tuvo la oportunidad de compartir y realizar una convivencia con el fin de despedir el semestre.<\/p>\n<p>[multimedia id=&#8221;1&#8243;]<\/p>\n<p>&nbsp;<\/p>\n"},"excerpt":{"rendered":"<p>En esta instancia, a trav\u00e9s de las Comunidades de curso, los estudiantes pudieron revisar y reestructurar en caso de ser necesario, su \u201cContrato de curso\u201d\u009d (compromisos y normas que establecieron los alumnos junto a su profesor\/a desde principio de a\u00f1o con buenas pr\u00e1cticas de convivencia), con el fin de visualizar fortalezas y debilidades durante el [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":11307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-11303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Segunda Jornada de Convivencia Escolar - Colegio Pumahue Chicauma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Segunda Jornada de Convivencia Escolar - Colegio Pumahue Chicauma\" \/>\n<meta property=\"og:description\" content=\"En esta instancia, a trav\u00e9s de las Comunidades de curso, los estudiantes pudieron revisar y reestructurar en caso de ser necesario, su \u201cContrato de curso\u201d\u009d (compromisos y normas que establecieron los alumnos junto a su profesor\/a desde principio de a\u00f1o con buenas pr\u00e1cticas de convivencia), con el fin de visualizar fortalezas y debilidades durante el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Pumahue Chicauma\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/ColegiosPumahue\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-30T19:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2022\/06\/Untitled-design-2022-06-30T145932.915.png\" \/>\n\t<meta property=\"og:image:width\" content=\"836\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"jorgedelcampo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"jorgedelcampo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/\"},\"author\":{\"name\":\"jorgedelcampo\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#\\\/schema\\\/person\\\/0debeea140e397b5d490ee7e553255d8\"},\"headline\":\"Segunda Jornada de Convivencia Escolar\",\"datePublished\":\"2022-06-30T19:00:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/\"},\"wordCount\":138,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/wp-content\\\/uploads\\\/sites\\\/47\\\/2022\\\/06\\\/Untitled-design-2022-06-30T145932.915.png\",\"articleSection\":[\"Vida escolar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/\",\"url\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/\",\"name\":\"Segunda Jornada de Convivencia Escolar - Colegio Pumahue Chicauma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/wp-content\\\/uploads\\\/sites\\\/47\\\/2022\\\/06\\\/Untitled-design-2022-06-30T145932.915.png\",\"datePublished\":\"2022-06-30T19:00:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/wp-content\\\/uploads\\\/sites\\\/47\\\/2022\\\/06\\\/Untitled-design-2022-06-30T145932.915.png\",\"contentUrl\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/wp-content\\\/uploads\\\/sites\\\/47\\\/2022\\\/06\\\/Untitled-design-2022-06-30T145932.915.png\",\"width\":836,\"height\":523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/noticias\\\/segunda-jornada-de-convivencia-escolar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segunda Jornada de Convivencia Escolar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#website\",\"url\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/\",\"name\":\"Colegio Pumahue Chicauma\",\"description\":\"Parte de Cognita Schools\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#organization\",\"name\":\"Colegio Pumahue Chicauma\",\"url\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/wp-content\\\/uploads\\\/sites\\\/47\\\/2025\\\/02\\\/cropped-logo_Pumahue_.png\",\"contentUrl\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/wp-content\\\/uploads\\\/sites\\\/47\\\/2025\\\/02\\\/cropped-logo_Pumahue_.png\",\"width\":512,\"height\":512,\"caption\":\"Colegio Pumahue Chicauma\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/ColegiosPumahue\",\"https:\\\/\\\/www.instagram.com\\\/colegiopumahue_chicauma\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@CognitaChile\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pumahue.cl\\\/chicauma\\\/#\\\/schema\\\/person\\\/0debeea140e397b5d490ee7e553255d8\",\"name\":\"jorgedelcampo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a315f521213b2dc91dbda9bf799f711c8a98ab6f5606ec42cf5b33d1e762e8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a315f521213b2dc91dbda9bf799f711c8a98ab6f5606ec42cf5b33d1e762e8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a315f521213b2dc91dbda9bf799f711c8a98ab6f5606ec42cf5b33d1e762e8a?s=96&d=mm&r=g\",\"caption\":\"jorgedelcampo\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Segunda Jornada de Convivencia Escolar - Colegio Pumahue Chicauma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/","og_locale":"es_ES","og_type":"article","og_title":"Segunda Jornada de Convivencia Escolar - Colegio Pumahue Chicauma","og_description":"En esta instancia, a trav\u00e9s de las Comunidades de curso, los estudiantes pudieron revisar y reestructurar en caso de ser necesario, su \u201cContrato de curso\u201d\u009d (compromisos y normas que establecieron los alumnos junto a su profesor\/a desde principio de a\u00f1o con buenas pr\u00e1cticas de convivencia), con el fin de visualizar fortalezas y debilidades durante el [&hellip;]","og_url":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/","og_site_name":"Colegio Pumahue Chicauma","article_publisher":"http:\/\/www.facebook.com\/ColegiosPumahue","article_published_time":"2022-06-30T19:00:11+00:00","og_image":[{"width":836,"height":523,"url":"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2022\/06\/Untitled-design-2022-06-30T145932.915.png","type":"image\/png"}],"author":"jorgedelcampo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"jorgedelcampo","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/#article","isPartOf":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/"},"author":{"name":"jorgedelcampo","@id":"https:\/\/www.pumahue.cl\/chicauma\/#\/schema\/person\/0debeea140e397b5d490ee7e553255d8"},"headline":"Segunda Jornada de Convivencia Escolar","datePublished":"2022-06-30T19:00:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/"},"wordCount":138,"commentCount":0,"publisher":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/#organization"},"image":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2022\/06\/Untitled-design-2022-06-30T145932.915.png","articleSection":["Vida escolar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/","url":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/","name":"Segunda Jornada de Convivencia Escolar - Colegio Pumahue Chicauma","isPartOf":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/#primaryimage"},"image":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2022\/06\/Untitled-design-2022-06-30T145932.915.png","datePublished":"2022-06-30T19:00:11+00:00","breadcrumb":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/#primaryimage","url":"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2022\/06\/Untitled-design-2022-06-30T145932.915.png","contentUrl":"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2022\/06\/Untitled-design-2022-06-30T145932.915.png","width":836,"height":523},{"@type":"BreadcrumbList","@id":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/segunda-jornada-de-convivencia-escolar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pumahue.cl\/chicauma\/"},{"@type":"ListItem","position":2,"name":"Segunda Jornada de Convivencia Escolar"}]},{"@type":"WebSite","@id":"https:\/\/www.pumahue.cl\/chicauma\/#website","url":"https:\/\/www.pumahue.cl\/chicauma\/","name":"Colegio Pumahue Chicauma","description":"Parte de Cognita Schools","publisher":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pumahue.cl\/chicauma\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pumahue.cl\/chicauma\/#organization","name":"Colegio Pumahue Chicauma","url":"https:\/\/www.pumahue.cl\/chicauma\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pumahue.cl\/chicauma\/#\/schema\/logo\/image\/","url":"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2025\/02\/cropped-logo_Pumahue_.png","contentUrl":"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2025\/02\/cropped-logo_Pumahue_.png","width":512,"height":512,"caption":"Colegio Pumahue Chicauma"},"image":{"@id":"https:\/\/www.pumahue.cl\/chicauma\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/ColegiosPumahue","https:\/\/www.instagram.com\/colegiopumahue_chicauma\/","https:\/\/www.youtube.com\/@CognitaChile"]},{"@type":"Person","@id":"https:\/\/www.pumahue.cl\/chicauma\/#\/schema\/person\/0debeea140e397b5d490ee7e553255d8","name":"jorgedelcampo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4a315f521213b2dc91dbda9bf799f711c8a98ab6f5606ec42cf5b33d1e762e8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a315f521213b2dc91dbda9bf799f711c8a98ab6f5606ec42cf5b33d1e762e8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a315f521213b2dc91dbda9bf799f711c8a98ab6f5606ec42cf5b33d1e762e8a?s=96&d=mm&r=g","caption":"jorgedelcampo"}}]}},"previous_post_ID":11296,"previous_post_title":"An international connection with Hydesville Tower School in the UK!","previous_post_excerpt":"Today our PK-B pupils connected through TEAMS with pupils from Hydesville Tower School in England, it was a nice activity for both schools, they were able to greet each other, meet and dance together. During the second half of the year we will continue to do this type of activities in order to create a [&hellip;]","previous_post_link":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/an-international-connection-with-hydesville-tower-school-in-the-uk\/","previous_post_class":["post-11296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar"],"next_post_ID":11313,"next_post_title":"Cierre de Talleres y Academias 1\u00b0 Semestre 2022","next_post_excerpt":"Los d\u00edas mi\u00e9rcoles 29 y jueves 30 de junio, se realiz\u00f3 el cierre de Talleres y Academias de nuestro colegio, correspondientes al primer semestre 2022. Con la asistencia de nuestras familias, nuestros estudiantes demostraron sus avances y la alegr\u00eda de ser parte de las actividades que como colegio seguiremos potenciando, a trav\u00e9s del retorno a [&hellip;]","next_post_link":"https:\/\/www.pumahue.cl\/chicauma\/noticias\/cierre-de-talleres-y-academias-1-semestre-2022\/","next_post_class":["post-11313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.pumahue.cl\/chicauma\/wp-content\/uploads\/sites\/47\/2022\/06\/Untitled-design-2022-06-30T145932.915.png","_links":{"self":[{"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/posts\/11303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/comments?post=11303"}],"version-history":[{"count":0,"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/posts\/11303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/media\/11307"}],"wp:attachment":[{"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/media?parent=11303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/categories?post=11303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pumahue.cl\/chicauma\/wp-json\/wp\/v2\/tags?post=11303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}