{"id":125997,"date":"2025-08-04T13:06:34","date_gmt":"2025-08-04T17:06:34","guid":{"rendered":"https:\/\/www.pumahue.cl\/penalolen\/?p=125997"},"modified":"2025-08-14T13:21:53","modified_gmt":"2025-08-14T17:21:53","slug":"colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole","status":"publish","type":"post","link":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/","title":{"rendered":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole"},"content":{"rendered":"<p>El pasado 16 de junio, en la Municipalidad de Pe\u00f1alol\u00e9n, se llev\u00f3 a cabo la esperada <b>Copa Interescolar de Nataci\u00f3n Soprole<\/b>, un evento que reuni\u00f3 a 53 colegios en una emocionante competencia. Con gran orgullo, el <b>Colegio Pumahue Pe\u00f1alol\u00e9n<\/b> se complace en anunciar que nuestro equipo obtuvo un destacado <b>tercer lugar<\/b> en la clasificaci\u00f3n general.<\/p>\n<h4><b>Talento y Esfuerzo<\/b><\/h4>\n<p>Este significativo logro es el resultado del esfuerzo, la disciplina y el talento de nuestros atletas, quienes demostraron un compromiso excepcional para representar al colegio. Su destacada participaci\u00f3n les permiti\u00f3 dejar el nombre de nuestra instituci\u00f3n en alto, reafirmando el valor del deporte en la formaci\u00f3n de nuestros estudiantes.<\/p>\n<h4><b>Felicitaciones a Nuestros Destacados Atletas<\/b><\/h4>\n<p>Extendemos una calurosa felicitaci\u00f3n a los diez estudiantes que, con su pasi\u00f3n y dedicaci\u00f3n, hicieron posible este triunfo. Nos llenan de orgullo los siguientes atletas:<\/p>\n<ul>\n<li>Renata Navas (Categor\u00eda 11-12 a\u00f1os)<\/li>\n<li>Florencia Nietzschmann (Categor\u00eda 11-12 a\u00f1os)<\/li>\n<li>Matias Oyarz\u00fan (Categor\u00eda 9-10 a\u00f1os)<\/li>\n<li>Nicolas Oyarz\u00fan (Categor\u00eda 11-12 a\u00f1os)<\/li>\n<li>Tomas Oyarz\u00fan (Categor\u00eda 13-17 a\u00f1os)<\/li>\n<li>Javiera Polverrelli (Categor\u00eda 9 a\u00f1os)<\/li>\n<li>Juan Ignacio Polverelli (Categor\u00eda 13-17 a\u00f1os)<\/li>\n<li>Diego Ramirez (Categor\u00eda 11-12 a\u00f1os)<\/li>\n<li>Emilio Reyes (Categor\u00eda 9-10 a\u00f1os)<\/li>\n<li>Crist\u00f3bal Vega (Categor\u00eda 11-12 a\u00f1os)<\/li>\n<\/ul>\n<p>\u00a1Felicitamos a todos nuestros deportistas por este merecido logro que nos inspira a seguir fomentando el deporte y la sana competencia en nuestra comunidad!<\/p>\n"},"excerpt":{"rendered":"<p>El pasado 16 de junio, en la Municipalidad de Pe\u00f1alol\u00e9n, se llev\u00f3 a cabo la esperada Copa Interescolar de Nataci\u00f3n Soprole, un evento que reuni\u00f3 a 53 colegios en una emocionante competencia. Con gran orgullo, el Colegio Pumahue Pe\u00f1alol\u00e9n se complace en anunciar que nuestro equipo obtuvo un destacado tercer lugar en la clasificaci\u00f3n general. [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":125998,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[78,58,75,73,74,72,77,76],"class_list":["post-125997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar","tag-atletas-pumahue-penalolen","tag-colegio-pumahue-penalolen","tag-competencia-interescolar","tag-copa-soprole","tag-deporte-escolar","tag-natacion","tag-orgullo-escolar","tag-tercer-lugar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole - Colegio Pumahue Pe\u00f1alol\u00e9n<\/title>\n<meta name=\"description\" content=\"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole - Colegio Pumahue Pe\u00f1alol\u00e9n\" \/>\n<meta property=\"og:description\" content=\"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Pumahue Pe\u00f1alol\u00e9n\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/ColegiosPumahue\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T17:06:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-14T17:21:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1116\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"danielacastro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"danielacastro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/\"},\"author\":{\"name\":\"danielacastro\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/5eb92a7b45165cdbdbb271bcdacc9d9e\"},\"headline\":\"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole\",\"datePublished\":\"2025-08-04T17:06:34+00:00\",\"dateModified\":\"2025-08-14T17:21:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/\"},\"wordCount\":263,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png\",\"keywords\":[\"Atletas Pumahue Pe\u00f1alol\u00e9n\",\"Colegio Pumahue Pe\u00f1alol\u00e9n\",\"Competencia Interescolar\",\"Copa Soprole\",\"Deporte Escolar\",\"Nataci\u00f3n\",\"Orgullo Escolar\",\"Tercer Lugar\"],\"articleSection\":[\"Vida Escolar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/\",\"name\":\"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole - Colegio Pumahue Pe\u00f1alol\u00e9n\",\"isPartOf\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png\",\"datePublished\":\"2025-08-04T17:06:34+00:00\",\"dateModified\":\"2025-08-14T17:21:53+00:00\",\"description\":\"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#primaryimage\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png\",\"contentUrl\":\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png\",\"width\":1116,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pumahue.cl\/penalolen\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#website\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/\",\"name\":\"Colegio Pumahue Pe\u00f1alol\u00e9n\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pumahue.cl\/penalolen\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#organization\",\"name\":\"Colegio Pumahue Pe\u00f1alol\u00e9n\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg\",\"contentUrl\":\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg\",\"width\":836,\"height\":523,\"caption\":\"Colegio Pumahue Pe\u00f1alol\u00e9n\"},\"image\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/ColegiosPumahue\",\"http:\/\/www.instagram.com\/colegiopumahue_penalolen\",\"https:\/\/www.youtube.com\/@CognitaChile\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/5eb92a7b45165cdbdbb271bcdacc9d9e\",\"name\":\"danielacastro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/16a603f2cc3ad485cabfe7c59b923050a809d8344cba940b4148737780592211?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/16a603f2cc3ad485cabfe7c59b923050a809d8344cba940b4148737780592211?s=96&d=mm&r=g\",\"caption\":\"danielacastro\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole - Colegio Pumahue Pe\u00f1alol\u00e9n","description":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/","og_locale":"es_ES","og_type":"article","og_title":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole - Colegio Pumahue Pe\u00f1alol\u00e9n","og_description":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole","og_url":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/","og_site_name":"Colegio Pumahue Pe\u00f1alol\u00e9n","article_publisher":"http:\/\/www.facebook.com\/ColegiosPumahue","article_published_time":"2025-08-04T17:06:34+00:00","article_modified_time":"2025-08-14T17:21:53+00:00","og_image":[{"width":1116,"height":550,"url":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png","type":"image\/png"}],"author":"danielacastro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"danielacastro","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#article","isPartOf":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/"},"author":{"name":"danielacastro","@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/5eb92a7b45165cdbdbb271bcdacc9d9e"},"headline":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole","datePublished":"2025-08-04T17:06:34+00:00","dateModified":"2025-08-14T17:21:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/"},"wordCount":263,"commentCount":0,"publisher":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/#organization"},"image":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png","keywords":["Atletas Pumahue Pe\u00f1alol\u00e9n","Colegio Pumahue Pe\u00f1alol\u00e9n","Competencia Interescolar","Copa Soprole","Deporte Escolar","Nataci\u00f3n","Orgullo Escolar","Tercer Lugar"],"articleSection":["Vida Escolar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/","url":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/","name":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole - Colegio Pumahue Pe\u00f1alol\u00e9n","isPartOf":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#primaryimage"},"image":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png","datePublished":"2025-08-04T17:06:34+00:00","dateModified":"2025-08-14T17:21:53+00:00","description":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole","breadcrumb":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#primaryimage","url":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png","contentUrl":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png","width":1116,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/colegio-pumahue-penalolen-obtiene-un-destacado-tercer-lugar-en-la-copa-interescolar-de-natacion-soprole\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pumahue.cl\/penalolen\/"},{"@type":"ListItem","position":2,"name":"Colegio Pumahue Pe\u00f1alol\u00e9n Obtiene un Destacado Tercer Lugar en la Copa Interescolar de Nataci\u00f3n Soprole"}]},{"@type":"WebSite","@id":"https:\/\/www.pumahue.cl\/penalolen\/#website","url":"https:\/\/www.pumahue.cl\/penalolen\/","name":"Colegio Pumahue Pe\u00f1alol\u00e9n","description":"","publisher":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pumahue.cl\/penalolen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pumahue.cl\/penalolen\/#organization","name":"Colegio Pumahue Pe\u00f1alol\u00e9n","url":"https:\/\/www.pumahue.cl\/penalolen\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/logo\/image\/","url":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg","contentUrl":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg","width":836,"height":523,"caption":"Colegio Pumahue Pe\u00f1alol\u00e9n"},"image":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/ColegiosPumahue","http:\/\/www.instagram.com\/colegiopumahue_penalolen","https:\/\/www.youtube.com\/@CognitaChile"]},{"@type":"Person","@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/5eb92a7b45165cdbdbb271bcdacc9d9e","name":"danielacastro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/16a603f2cc3ad485cabfe7c59b923050a809d8344cba940b4148737780592211?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16a603f2cc3ad485cabfe7c59b923050a809d8344cba940b4148737780592211?s=96&d=mm&r=g","caption":"danielacastro"}}]}},"jetpack_featured_media_url":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2025\/08\/Colegio-Pumahue-Penalolen-Natacion-Copa-Soprole.png","previous_post_ID":125994,"previous_post_title":"Proyectos CAMPUR en el Colegio Pumahue Pe\u00f1alol\u00e9n Incentivan la Solidaridad","previous_post_excerpt":"El Colegio Pumahue Pe\u00f1alol\u00e9n celebra los exitosos Proyectos CAMPUR, una iniciativa que demuestra el esp\u00edritu de colaboraci\u00f3n y solidaridad de sus estudiantes en diversos niveles educativos. Estos proyectos han abarcado desde acciones comunitarias hasta el uso innovador de la tecnolog\u00eda, reflejando el compromiso y la creatividad de toda la comunidad escolar. Solidaridad y Comunidad en [&hellip;]","previous_post_link":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/proyectos-campur-en-el-colegio-pumahue-penalolen-incentivan-la-solidaridad\/","previous_post_class":["post-125994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar","tag-actividad-solidaria","tag-colegio-pumahue-penalolen","tag-comunidad-escolar","tag-educacion-parvularia","tag-innovacion-educativa","tag-proyecto-campur","tag-solidaridad"],"next_post_ID":126003,"next_post_title":"Pumahue Pe\u00f1alol\u00e9n y su compromiso con el reciclaje","next_post_excerpt":"En el Colegio Pumahue Pe\u00f1alol\u00e9n, el compromiso con el medio ambiente es m\u00e1s que una lecci\u00f3n: es una acci\u00f3n concreta. Recientemente, nuestra comunidad educativa demostr\u00f3 este valor participando en una significativa campa\u00f1a de reciclaje que uni\u00f3 a estudiantes, familias y profesores con un objetivo com\u00fan: cuidar nuestro planeta y ayudar a quienes m\u00e1s lo necesitan. [&hellip;]","next_post_link":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/pumahue-penalolen-y-su-compromiso-con-el-reciclaje\/","next_post_class":["post-126003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar","tag-brigada-ecologica","tag-campana-reciclaje","tag-colegios-penalolen","tag-damas-de-cafe","tag-educacion-ambiental","tag-medio-ambiente","tag-pumahue-penalolen","tag-punto-limpio-penalolen","tag-reciclaje","tag-reciclaje-escolar","tag-responsabilidad-social"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/posts\/125997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/comments?post=125997"}],"version-history":[{"count":1,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/posts\/125997\/revisions"}],"predecessor-version":[{"id":125999,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/posts\/125997\/revisions\/125999"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/media\/125998"}],"wp:attachment":[{"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/media?parent=125997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/categories?post=125997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/tags?post=125997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}