{"id":23494,"date":"2022-12-12T15:44:52","date_gmt":"2022-12-12T18:44:52","guid":{"rendered":"http:\/\/pumahue.cl\/penalolen\/?p=23494"},"modified":"2022-12-12T15:44:52","modified_gmt":"2022-12-12T18:44:52","slug":"cierre-programa-selp-2022","status":"publish","type":"post","link":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/","title":{"rendered":"Cierre Programa SELP 2022"},"content":{"rendered":"<p>Nuestros nuevos alumnos 2022 del curr\u00edculum Biling\u00fce, que participaron del programa SELP, recibieron un diploma como parte del cierre de sus actividades.<\/p>\n<p>El programa de nivelaci\u00f3n idiom\u00e1tica SELP est\u00e1 enfocado en los estudiantes que ingresan al programa biling\u00fce por primera vez y que requieren de apoyo adicional, seg\u00fan la entrevista de admisi\u00f3n inicial con el Coordinador del Programa Biling\u00fce (BAL).<\/p>\n<p>Para el 2022, el programa se extendi\u00f3, cubriendo todos los cursos biling\u00fces de primero a sexto b\u00e1sico, alumnos que participaron de diversas din\u00e1micas de apoyo ling\u00fc\u00edstico y habilidades comunicativas durante todo el a\u00f1o.<\/p>\n<p>Nuestro programa no solo potencia el desempe\u00f1o acad\u00e9mico, tambi\u00e9n es una instancia para que los ni\u00f1os se relacionen con compa\u00f1eros de otros cursos y niveles, aportando con parte de sus primeros lazos en su colegio y como miembros de la comunidad.<\/p>\n<p>Felicitamos a todos nuestros estudiantes quienes dieron todo de s\u00ed durante el a\u00f1o y que terminaron el programa con un desempe\u00f1o y participaci\u00f3n incre\u00edbles.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><strong>Colegio Pumahue Pe\u00f1alol\u00e9n<\/strong><\/p>\n<p>\u00c2\u00a0[multimedia id=&#8221;1&#8243;]<\/p>\n"},"excerpt":{"rendered":"<p>Nuestros nuevos alumnos 2022 del curr\u00edculum Biling\u00fce, que participaron del programa SELP, recibieron un diploma como parte del cierre de sus actividades. El programa de nivelaci\u00f3n idiom\u00e1tica SELP est\u00e1 enfocado en los estudiantes que ingresan al programa biling\u00fce por primera vez y que requieren de apoyo adicional, seg\u00fan la entrevista de admisi\u00f3n inicial con el [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":23497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cierre Programa SELP 2022 - Colegio Pumahue Pe\u00f1alol\u00e9n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cierre Programa SELP 2022 - Colegio Pumahue Pe\u00f1alol\u00e9n\" \/>\n<meta property=\"og:description\" content=\"Nuestros nuevos alumnos 2022 del curr\u00edculum Biling\u00fce, que participaron del programa SELP, recibieron un diploma como parte del cierre de sus actividades. El programa de nivelaci\u00f3n idiom\u00e1tica SELP est\u00e1 enfocado en los estudiantes que ingresan al programa biling\u00fce por primera vez y que requieren de apoyo adicional, seg\u00fan la entrevista de admisi\u00f3n inicial con el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Pumahue Pe\u00f1alol\u00e9n\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/ColegiosPumahue\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-12T18:44:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"836\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"danielacastro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"danielacastro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/\"},\"author\":{\"name\":\"danielacastro\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/5eb92a7b45165cdbdbb271bcdacc9d9e\"},\"headline\":\"Cierre Programa SELP 2022\",\"datePublished\":\"2022-12-12T18:44:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/\"},\"wordCount\":189,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Vida Escolar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/\",\"name\":\"Cierre Programa SELP 2022 - Colegio Pumahue Pe\u00f1alol\u00e9n\",\"isPartOf\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-12-12T18:44:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pumahue.cl\/penalolen\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cierre Programa SELP 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#website\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/\",\"name\":\"Colegio Pumahue Pe\u00f1alol\u00e9n\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pumahue.cl\/penalolen\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#organization\",\"name\":\"Colegio Pumahue Pe\u00f1alol\u00e9n\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg\",\"contentUrl\":\"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg\",\"width\":836,\"height\":523,\"caption\":\"Colegio Pumahue Pe\u00f1alol\u00e9n\"},\"image\":{\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/ColegiosPumahue\",\"http:\/\/www.instagram.com\/colegiopumahue_penalolen\",\"https:\/\/www.youtube.com\/@CognitaChile\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/5eb92a7b45165cdbdbb271bcdacc9d9e\",\"name\":\"danielacastro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/16a603f2cc3ad485cabfe7c59b923050a809d8344cba940b4148737780592211?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/16a603f2cc3ad485cabfe7c59b923050a809d8344cba940b4148737780592211?s=96&d=mm&r=g\",\"caption\":\"danielacastro\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cierre Programa SELP 2022 - Colegio Pumahue Pe\u00f1alol\u00e9n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/","og_locale":"es_ES","og_type":"article","og_title":"Cierre Programa SELP 2022 - Colegio Pumahue Pe\u00f1alol\u00e9n","og_description":"Nuestros nuevos alumnos 2022 del curr\u00edculum Biling\u00fce, que participaron del programa SELP, recibieron un diploma como parte del cierre de sus actividades. El programa de nivelaci\u00f3n idiom\u00e1tica SELP est\u00e1 enfocado en los estudiantes que ingresan al programa biling\u00fce por primera vez y que requieren de apoyo adicional, seg\u00fan la entrevista de admisi\u00f3n inicial con el [&hellip;]","og_url":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/","og_site_name":"Colegio Pumahue Pe\u00f1alol\u00e9n","article_publisher":"http:\/\/www.facebook.com\/ColegiosPumahue","article_published_time":"2022-12-12T18:44:52+00:00","og_image":[{"width":836,"height":523,"url":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg","type":"image\/jpeg"}],"author":"danielacastro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"danielacastro","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#article","isPartOf":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/"},"author":{"name":"danielacastro","@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/5eb92a7b45165cdbdbb271bcdacc9d9e"},"headline":"Cierre Programa SELP 2022","datePublished":"2022-12-12T18:44:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/"},"wordCount":189,"commentCount":0,"publisher":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/#organization"},"image":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#primaryimage"},"thumbnailUrl":"","articleSection":["Vida Escolar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/","url":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/","name":"Cierre Programa SELP 2022 - Colegio Pumahue Pe\u00f1alol\u00e9n","isPartOf":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-12-12T18:44:52+00:00","breadcrumb":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/cierre-programa-selp-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pumahue.cl\/penalolen\/"},{"@type":"ListItem","position":2,"name":"Cierre Programa SELP 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.pumahue.cl\/penalolen\/#website","url":"https:\/\/www.pumahue.cl\/penalolen\/","name":"Colegio Pumahue Pe\u00f1alol\u00e9n","description":"","publisher":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pumahue.cl\/penalolen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.pumahue.cl\/penalolen\/#organization","name":"Colegio Pumahue Pe\u00f1alol\u00e9n","url":"https:\/\/www.pumahue.cl\/penalolen\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/logo\/image\/","url":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg","contentUrl":"https:\/\/www.pumahue.cl\/penalolen\/wp-content\/uploads\/sites\/44\/2020\/03\/LOGO-PUMAHUE-PARA-web.jpg","width":836,"height":523,"caption":"Colegio Pumahue Pe\u00f1alol\u00e9n"},"image":{"@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/ColegiosPumahue","http:\/\/www.instagram.com\/colegiopumahue_penalolen","https:\/\/www.youtube.com\/@CognitaChile"]},{"@type":"Person","@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/5eb92a7b45165cdbdbb271bcdacc9d9e","name":"danielacastro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.pumahue.cl\/penalolen\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/16a603f2cc3ad485cabfe7c59b923050a809d8344cba940b4148737780592211?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16a603f2cc3ad485cabfe7c59b923050a809d8344cba940b4148737780592211?s=96&d=mm&r=g","caption":"danielacastro"}}]}},"jetpack_featured_media_url":"","previous_post_ID":23455,"previous_post_title":"El Viejito Pascuero visita Pumahue Pe\u00f1alol\u00e9n","previous_post_excerpt":"Con mucha emoci\u00f3n los ni\u00f1os y ni\u00f1as de Educaci\u00f3n Parvularia recibieron al Viejito Pascuero, en una visita cargada de alegr\u00eda y de emociones en la v\u00edspera de las fiestas de fin de a\u00f1o y como un regalo especial como t\u00e9rmino del 2022. Agradecemos al Centro de Padres y Apoderados por tan lindo regalo para nuestros [&hellip;]","previous_post_link":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/el-viejito-pascuero-visita-pumahue-penalolen\/","previous_post_class":["post-23455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar"],"next_post_ID":23545,"next_post_title":"Ceremonia de Premiaci\u00f3n de K\u00ednder 2022","next_post_excerpt":"Con mucha alegr\u00eda y entusiasmo los ni\u00f1os de K\u00ednder de Pumahue Pe\u00f1alol\u00e9n participaron de su Ceremonia de Finalizaci\u00f3n, acto en el que fueron acompa\u00f1ados por sus misses y sus familias, siendo una ocasi\u00f3n muy especial, donde fueron premiados recibiendo todos los aplausos de los presentes. Felicitaciones a todos nuestros ni\u00f1os y ni\u00f1as del nivel, el [&hellip;]","next_post_link":"https:\/\/www.pumahue.cl\/penalolen\/noticias\/ceremonia-de-premiacion-de-kinder-2022\/","next_post_class":["post-23545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vida-escolar"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/posts\/23494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/comments?post=23494"}],"version-history":[{"count":0,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/posts\/23494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/media?parent=23494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/categories?post=23494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pumahue.cl\/penalolen\/wp-json\/wp\/v2\/tags?post=23494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}